{"id":18810,"date":"2020-02-18T11:31:43","date_gmt":"2020-02-18T11:31:43","guid":{"rendered":"https:\/\/hisarkayaemlak.com\/?page_id=18810"},"modified":"2026-06-02T07:33:51","modified_gmt":"2026-06-02T07:33:51","slug":"home","status":"publish","type":"page","link":"https:\/\/hisarkayaemlak.com\/en\/","title":{"rendered":"HOME"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18810\" class=\"elementor elementor-18810 elementor-17972\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b147f27 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"b147f27\" data-element_type=\"section\" data-e-type=\"section\" id=\"hero-banner\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c7ef66\" data-id=\"1c7ef66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-832f136 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"832f136\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b488bd4\" data-id=\"b488bd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f1a2d6 animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"5f1a2d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Just Imagine It\u2014Leave the Rest to Us. <\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">A Guide to Real Estate Investment in Turkey<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de02c12 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de02c12\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c73b61\" data-id=\"5c73b61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a474c0 elementor-button-align-stretch elementor-widget elementor-widget-houzez_elementor_search_builder\" data-id=\"3a474c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_search_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <form class=\"houzez-search-form-js houzez-search-builder-form-js\" id=\"houzez-search-3a474c0\" method=\"get\" action=\"https:\/\/hisarkayaemlak.com\/en\/search-results\/\" >\n\n            \n            <ul id=\"houzez-search-tabs-wrap\" class=\"houzez-status-tabs nav nav-pills\" role=\"tablist\" data-bs-toggle=\"buttons\">\n            \n                                <li class=\"nav-item\">\n                    <a class=\"nav-link active\" data-val=\"\" data-bs-toggle=\"pill\" href=\"#\" role=\"tab\" aria-bs-selected=\"true\">\n                        ALL                    <\/a>\n                <\/li>\n                \n                <li class=\"nav-item\">\n                                <a class=\"status-tab-js nav-link \" data-val=\"for-rent\" data-bs-toggle=\"pill\" href=\"#\" role=\"tab\" aria-bs-selected=\"true\">\n                                    FOR RENT\n                                <\/a>\n                            <\/li><li class=\"nav-item\">\n                                <a class=\"status-tab-js nav-link \" data-val=\"for-sale\" data-bs-toggle=\"pill\" href=\"#\" role=\"tab\" aria-bs-selected=\"true\">\n                                    FOR SALE\n                                <\/a>\n                            <\/li>                <input type=\"hidden\" name=\"status[]\" id=\"search-tabs\" value=\"\">\n            <\/ul>\n            \n            <div class=\"houzez-search-builder-wrapper\">\n\n                <div class=\"houzez-ele-search-form-wrapper elementor-form-fields-wrapper elementor-labels-above\">\n\n                                            <div class=\"elementor-field-group elementor-column form-group elementor-field-group-field-types elementor-col-25 elementor-sm-100\">\n                    <label for=\"form-field-field-types\" class=\"elementor-field-label\">Search by Keyword<\/label><input type=\"text\" size=\"1\" name=\"keyword\" id=\"form-field-field-types\" value=\"\" class=\"elementor-field form-control elementor-size-sm elementor-field-textual houzez-keyword-autocomplete\" placeholder=\"Title, Region, Ad Type\"><div id=\"auto_complete_ajax\" class=\"auto-complete\"><\/div>                    <\/div>\n                                <div class=\"elementor-field-group elementor-column form-group elementor-field-group-9e1b7c6 elementor-col-20\">\n                    <label for=\"form-field-9e1b7c6\" class=\"elementor-field-label\">Ad Type<\/label>        <div class=\"elementor-field elementor-select-wrapper form-group\">\n            <select data-size=\"5\" name=\"type[]\" id=\"form-field-9e1b7c6\" class=\"selectpicker bs-select-hidden houzez-field-textual form-control elementor-size-sm \" data-none-results-text=\"E\u015fle\u015fen sonu\u00e7 yok {0}\">\n                <option value=\"\">Make a Selection<\/option><option data-ref=\"villa\"   value=\"villa\">Villa<\/option><option data-ref=\"apartment\"   value=\"apartment\">Apartment<\/option><option data-ref=\"commercial-real-estate\"   value=\"commercial-real-estate\">Commercial Real Estate<\/option><option data-ref=\"entire-building\"   value=\"entire-building\">Entire Building<\/option><option data-ref=\"land-plots\"   value=\"land-plots\">Land &amp; Plots<\/option><option data-ref=\"off-plan-property\"   value=\"off-plan-property\">Off-Plan Property<\/option><option data-ref=\"tourism-facility\"   value=\"tourism-facility\">Tourism Facility<\/option>            <\/select>\n        <\/div>\n                            <\/div>\n                                <div class=\"elementor-field-group elementor-column form-group elementor-field-group-6b0017d elementor-col-35\">\n                    <label for=\"form-field-6b0017d\" class=\"elementor-field-label\">REGION<\/label>        <div class=\"elementor-field elementor-select-wrapper form-group\">\n            <select data-size=\"5\" name=\"location[]\" id=\"form-field-6b0017d\" class=\"selectpicker bs-select-hidden houzez-field-textual form-control elementor-size-sm houzezSelectFilter houzezCityFilter houzezThirdList houzez-city-js\" data-none-results-text=\"E\u015fle\u015fen sonu\u00e7 yok {0}\" data-target=\"houzezFourthList\">\n                <option value=\"\">Make a Selection<\/option><option data-ref=\"fethiye\" data-belong=\"mugla\" data-subtext=\"MU\u011eLA\" value=\"fethiye\">FETH\u0130YE<\/option><option data-ref=\"calis-neighbourhood\" data-belong=\"\" value=\"calis-neighbourhood\"> - \u00c7al\u0131\u015f (Neighbourhood)<\/option><option data-ref=\"faralya-neighbourhood\" data-belong=\"\" value=\"faralya-neighbourhood\"> - Faralya (Neighbourhood)<\/option><option data-ref=\"fethiye-city-centre-neighbourhood\" data-belong=\"\" value=\"fethiye-city-centre-neighbourhood\"> - Fethiye City Centre (Neighbourhood)<\/option><option data-ref=\"gocek-neighbourhood\" data-belong=\"\" value=\"gocek-neighbourhood\"> - G\u00f6cek (Neighbourhood)<\/option><option data-ref=\"karagozler-neighbourhood\" data-belong=\"\" value=\"karagozler-neighbourhood\"> - Karag\u00f6zler (Neighbourhood)<\/option><option data-ref=\"kayakoy-neighbourhood\" data-belong=\"\" value=\"kayakoy-neighbourhood\"> - Kayak\u00f6y (Neighbourhood)<\/option><option data-ref=\"oludeniz-neighbourhood\" data-belong=\"\" value=\"oludeniz-neighbourhood\"> - \u00d6l\u00fcdeniz (Neighbourhood)<\/option><option data-ref=\"ovacik-neighbourhood\" data-belong=\"\" value=\"ovacik-neighbourhood\"> - Ovac\u0131k (Neighbourhood)<\/option><option data-ref=\"sovalye-adasi-neighbourhood\" data-belong=\"\" value=\"sovalye-adasi-neighbourhood\"> - \u015e\u00f6valye Adas\u0131 (Neighbourhood)<\/option><option data-ref=\"tasyaka-neighbourhood\" data-belong=\"\" value=\"tasyaka-neighbourhood\"> - Ta\u015fyaka (Neighbourhood)<\/option><option data-ref=\"yesiluzumlu-neighbourhood\" data-belong=\"\" value=\"yesiluzumlu-neighbourhood\"> - Ye\u015fil\u00fcz\u00fcml\u00fc (Neighbourhood)<\/option><option data-ref=\"istanbul\" data-belong=\"arnavutkoy\" data-subtext=\"ARNAVUTK\u00d6Y\" value=\"istanbul\">\u0130stanbul<\/option><option data-ref=\"kalkan-district-neighbourhood\" data-belong=\"antalya\" data-subtext=\"ANTALYA\" value=\"kalkan-district-neighbourhood\">Kalkan (District \/ Neighbourhood)<\/option><option data-ref=\"kas-district\" data-belong=\"antalya\" data-subtext=\"ANTALYA\" value=\"kas-district\">Ka\u015f (District)<\/option><option data-ref=\"mugla\" data-belong=\"fethiye\" data-subtext=\"FETH\u0130YE\" value=\"mugla\">MU\u011eLA<\/option><option data-ref=\"seydikemer-district\" data-belong=\"\" data-subtext=\"\" value=\"seydikemer-district\">SEYD\u0130KEMER (District)<\/option>            <\/select>\n        <\/div>\n                            <\/div>\n                                    <div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-20\">\n                                <button type=\"submit\" class=\"houzez-search-button btn-primary elementor-button elementor-size-sm\">\n                                                                            SHOW                                                                    <\/button>\n                            <\/div>\n                            \n                <\/div><!-- End main wrapper-->\n\n                            <\/div> <!-- End houzez-search-builder-wrapper -->\n        <\/form>\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fc59222 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6fc59222\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-766ac79d\" data-id=\"766ac79d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-35435fd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35435fd1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4540024e\" data-id=\"4540024e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61d75a7d elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"61d75a7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">LATEST PROPERTIES LISTED<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">Take a look at our latest listings and the newest properties we\u2019ve added\u2026\n<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-iej91kbmr elementor-widget elementor-widget-houzez_elementor_properties_carousel_v5\" data-id=\"iej91kbmr\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_properties_carousel_v5.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"property-carousel-module property-carousel-module-v5 property-carousel-module-v5-5cols houzez-carousel-arrows-5ZnFs\">\n            <div class=\"property-carousel-buttons-wrap \">\n                                <button type=\"button\" class=\"slick-prev-js-5ZnFs slick-prev btn-primary-outlined\">Prev<\/button>\n                <button type=\"button\" class=\"slick-next-js-5ZnFs slick-next btn-primary-outlined\">Next<\/button>\n                                            <\/div><!-- property-carousel-buttons-wrap -->\n\n            <div class=\"listing-view grid-view\">\n                <div id=\"houzez-properties-carousel-5ZnFs\" data-token=\"5ZnFs\" class=\"houzez-properties-carousel-js houzez-all-slider-wrap property-carousel-wrap-v5-5cols\">\n                    <div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20630\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1703_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1703_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1703_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1703_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1701_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1701_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1701_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1701_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1671_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1671_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1671_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1671_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1672_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1672_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1672_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1672_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1673_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1673_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1673_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1673_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1674_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1674_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1674_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1674_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1675_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1675_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1675_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1675_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1676_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1676_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1676_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1676_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20630\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20630\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20630 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20630\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/modern-21-garden-floor-apartment-for-sale-in-fethiye-deliktas-prime-location\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\u015f \u2013 Prime Location\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/modern-21-garden-floor-apartment-for-sale-in-fethiye-deliktas-prime-location\/\" role=\"link\">Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\u015f \u2013 Prime Location<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $174,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tApartment\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">2<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathroom:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">68<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20548\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3287-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3287-2_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3287-2_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3287-2_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3288_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289-2_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289-2_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289-2_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3292-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3295-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3290-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3291_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3292_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3293_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-rent\/\" class=\"hz-label label label-color-336\">\n\t\t\t\t\tFor Rent\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20548\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20548\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20548 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20548\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-31-villa-for-sale-in-ovacik-fethiye-rental-guarantee-private-concept\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Luxury 3+1 Villa for Sale in Ovac\u0131k, Fethiye \u2013 Rental Guarantee &amp; Private Concept\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-31-villa-for-sale-in-ovacik-fethiye-rental-guarantee-private-concept\/\" role=\"link\">Luxury 3+1 Villa for Sale in Ovac\u0131k, Fethiye \u2013 Rental Guarantee &amp; Private Concept<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $750,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">280<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20080\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.42-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.42-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.46_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.43_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.45-1_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.37-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.47_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.48-1_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.37-3_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.37-4_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20080\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20080\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20080 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20080\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-21-at-11.38.42-2_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-outdoor-indoor-pool-villa-in-ovacik\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-21-at-11.38.42-2_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-outdoor-indoor-pool-villa-in-ovacik\/\" role=\"link\">LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $555,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">230<\/span> <span class=\"hz-figure area_postfix\">sq<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"18995\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A7084_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A6753_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A6742_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A6745_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A6750_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A6754_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A6758_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A6760_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A6762_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0B0A6764_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-rent\/\" class=\"label-status label status-color-242\">\n\t\t\t\t\tFOR RENT\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"18995\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"18995\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-18995 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"18995\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A7084_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-villa-suitable-for-turkcitizenship-with-sea-view-in-kalkan\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A7084_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-villa-suitable-for-turkcitizenship-with-sea-view-in-kalkan\/\" role=\"link\">LUXURY VILLA SUITABLE FOR TURKCITIZENSHIP WITH SEA VIEW IN KALKAN<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $840,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">300<\/span> <span class=\"hz-figure area_postfix\">sq<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"19672\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1135_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1135_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1135_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1135_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1136_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1136_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1136_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1136_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1137_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1137_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1137_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1137_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1138_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1138_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1138_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1138_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1139_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1139_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1139_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1139_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1140_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1140_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1140_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1140_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1141_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1141_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1141_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1141_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1142_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1142_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1142_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1142_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"19672\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"19672\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-19672 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"19672\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/21-apartment-with-pool-in-a-perfect-complex-in-fethiye-ovacik\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\u0130YE OVACIK\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/21-apartment-with-pool-in-a-perfect-complex-in-fethiye-ovacik\/\" role=\"link\">2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\u0130YE OVACIK<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $166,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tApartment\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">2<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">2<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">85<\/span> <span class=\"hz-figure area_postfix\">sq<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20126\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121354_0732_1777654914438_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121354_0732_1777654914438_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121402_0733_1777654914221_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121402_0733_1777654914221_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121402_0733_1777654914221_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121402_0733_1777654914221_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121426_0734_1777654913868_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121426_0734_1777654913868_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121426_0734_1777654913868_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121426_0734_1777654913868_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121504_0735_1777654913503_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121504_0735_1777654913503_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121504_0735_1777654913503_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121504_0735_1777654913503_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121704_0739_1777654911740_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121704_0739_1777654911740_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121704_0739_1777654911740_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121704_0739_1777654911740_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1267_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1267_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1267_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1267_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1268_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1268_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1268_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1268_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1269_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1269_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1269_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1269_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1270_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1270_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1270_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1270_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1271_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1271_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1271_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1271_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20126\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20126\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20126 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20126\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/detached-villa-with-private-garden-pool-fully-furnished\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Detached Villa with Private Garden, Pool &amp; Fully Furnished!\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/detached-villa-with-private-garden-pool-fully-furnished\/\" role=\"link\">Detached Villa with Private Garden, Pool &amp; Fully Furnished!<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $675,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">200<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"19888\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006582-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006582-2_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006582-2_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006582-2_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-3_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-3_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-3_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-3_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-4_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-4_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-4_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-4_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006608-2_result-2-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006608-2_result-2-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006608-2_result-2-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006608-2_result-2.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006634-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006634-2_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006634-2_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006634-2_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008238-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008241-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008241-2_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008241-2_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008241-2_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008242-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008242-2_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008242-2_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008242-2_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"19888\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"19888\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-19888 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"19888\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/41-detached-villa-in-580-m%c2%b2-land-in-fethiye-ovacik\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"4+1 DETACHED VILLA IN 580 m\u00b2 LAND IN FETH\u0130YE OVACIK\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/41-detached-villa-in-580-m%c2%b2-land-in-fethiye-ovacik\/\" role=\"link\">4+1 DETACHED VILLA IN 580 m\u00b2 LAND IN FETH\u0130YE OVACIK<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $500,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garages:<\/span> <span class=\"hz-figure\">2<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">396<\/span> <span class=\"hz-figure area_postfix\">sq<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20798\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1609_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1609_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1609_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1609_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1623_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1623_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1623_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1623_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1621_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1621_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1621_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1621_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1619_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1619_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1619_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1619_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1622_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1622_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1622_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1622_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1625_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1625_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1625_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1625_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1626_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1626_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1626_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1626_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1620_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1620_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1620_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1620_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20798\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20798\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20798 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20798\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/prime-investment-opportunity-in-the-heart-of-fethiye-brand-new-11-garden-apartment-for-sale-in-tuzla\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/prime-investment-opportunity-in-the-heart-of-fethiye-brand-new-11-garden-apartment-for-sale-in-tuzla\/\" role=\"link\">Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $149,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tApartment\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yatak:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathroom:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">50<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20751\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1473_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1473_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1473_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1473_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1473_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1473_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1473_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1473_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1467_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1467_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1467_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1467_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1442_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1442_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1442_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1442_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1443_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1443_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1443_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1443_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1446_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1446_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1446_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1446_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1444_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1444_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1444_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1444_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1445_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1445_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1445_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1445_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1447_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1447_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1447_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1447_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1448_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1448_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1448_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1448_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20751\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20751\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20751 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20751\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1473_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-4-bedroom-detached-villa-for-sale-near-oludeniz\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1473_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1473_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1473_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1473_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-4-bedroom-detached-villa-for-sale-near-oludeniz\/\" role=\"link\">Luxury 4-Bedroom Detached Villa for Sale Near Oludeniz<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $772,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">230<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20909\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1381_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1381_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1381_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1381_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1382_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1382_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1382_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1382_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1383_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1383_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1383_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1383_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1384_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1384_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1384_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1384_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1385_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1385_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1385_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1385_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1386_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1386_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1386_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1386_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1387_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1387_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1387_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1387_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1388_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1388_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1388_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1388_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1389_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1389_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1389_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1389_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20909\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20909\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20909 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20909\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/sophisticated-41-luxury-smart-villa-in-yesiluzumlu\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/sophisticated-41-luxury-smart-villa-in-yesiluzumlu\/\" role=\"link\">Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $445,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">300<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20404\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1647_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1647_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1647_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1647_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1648_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1648_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1648_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1648_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1649_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1649_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1649_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1649_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1650_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1650_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1650_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1650_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1651_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1651_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1651_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1651_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1652_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1652_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1652_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1652_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1653_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1653_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1653_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1653_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1654_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1654_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1654_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1654_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20404\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20404\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20404 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20404\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/exclusive-living-in-babatasi-fethiye-corner-plot-modern-architecture-customizable-41-luxury-villa\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Exclusive Living in Babata\u015f\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/exclusive-living-in-babatasi-fethiye-corner-plot-modern-architecture-customizable-41-luxury-villa\/\" role=\"link\">Exclusive Living in Babata\u015f\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $740,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">210<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>                <\/div><!-- carousel-wrap -->\n            <\/div><!-- listing-view grid-view -->\n            \n                    <\/div><!-- property-carousel-module -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0yzl87d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0yzl87d4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-chpxzwgui\" data-id=\"chpxzwgui\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5qofrmost elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"5qofrmost\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-fcjwcjlpf\" data-id=\"fcjwcjlpf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-p576u8s51 elementor-widget elementor-widget-spacer\" data-id=\"p576u8s51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-qghdz5kl9\" data-id=\"qghdz5kl9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-z0y6z93uc elementor-widget elementor-widget-spacer\" data-id=\"z0y6z93uc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5slw6axrc elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"5slw6axrc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">EXCLUSIVE LUXURY REAL ESTATE AND INVESTMENT SERVICES<\/h2>\n                \n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-la4un3i3v\" data-id=\"la4un3i3v\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-zymshkum7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"zymshkum7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a7xefogrl elementor-invisible\" data-id=\"a7xefogrl\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dupefsmz2 elementor-widget elementor-widget-image\" data-id=\"dupefsmz2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/personalized-service\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2020\/03\/205.jpg\" class=\"attachment-large size-large wp-image-17330\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-jkovtwn5y elementor-widget elementor-widget-heading\" data-id=\"jkovtwn5y\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Personalized Service<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5alfc3nn elementor-widget elementor-widget-text-editor\" data-id=\"f5alfc3nn\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>By thoroughly understanding your needs, preferences, and lifestyle, we carefully select the luxury residences that best suit you.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-hqwsd05sc elementor-invisible\" data-id=\"hqwsd05sc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:800}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-m1yri7pwe elementor-widget elementor-widget-image\" data-id=\"m1yri7pwe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/comprehensive-market-analysis\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2020\/03\/206.jpg\" class=\"attachment-large size-large wp-image-17329\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-kcsglrswo elementor-widget elementor-widget-heading\" data-id=\"kcsglrswo\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comprehensive Market Analysis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ivdp3zrd elementor-widget elementor-widget-text-editor\" data-id=\"9ivdp3zrd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-568665d e-flex e-con-boxed e-con e-child\" data-id=\"568665d\" data-element_type=\"container\" data-e-type=\"container\">\n<div class=\"e-con-inner\">\n<div class=\"elementor-element elementor-element-38171cc elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"38171cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n<p class=\"elementor-heading-title elementor-size-default\">By providing in-depth analysis based on current trends, we help you identify the most accurate and profitable investment opportunities.\u00a0<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-f51eafe e-flex e-con-boxed e-con e-child\" data-id=\"f51eafe\" data-element_type=\"container\" data-e-type=\"container\">\n<div class=\"e-con-inner\">\n<div class=\"elementor-element elementor-element-66a897d elementor-widget elementor-widget-Houzez_Banner_Image\" data-id=\"66a897d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Houzez_Banner_Image.default\">\n<div class=\"elementor-widget-container optml-bg-lazyloaded\">\n<div class=\"banner-image-module d-flex justify-content-center align-items-center\">\u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-p3xq4p39o elementor-invisible\" data-id=\"p3xq4p39o\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:1200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10lws6rwx elementor-widget elementor-widget-image\" data-id=\"10lws6rwx\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/we-operate-globally\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"688\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2023\/02\/chicago-07.jpg\" class=\"attachment-large size-large wp-image-17710\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-novesnidz elementor-widget elementor-widget-heading\" data-id=\"novesnidz\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We Operate Globally<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-gkq98n987 elementor-widget elementor-widget-text-editor\" data-id=\"gkq98n987\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b217c61 e-flex e-con-boxed e-con e-parent optml-bg-lazyloaded e-lazyloaded animated fadeIn\" data-id=\"b217c61\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n<div class=\"e-con-inner\">\n<div class=\"elementor-element elementor-element-f51eafe e-flex e-con-boxed e-con e-child\" data-id=\"f51eafe\" data-element_type=\"container\" data-e-type=\"container\">\n<div class=\"e-con-inner\">\n<div class=\"elementor-element elementor-element-358900f elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"358900f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n<p class=\"elementor-heading-title elementor-size-default\">We have a global vision and an extensive network. We offer a wide range of real estate properties for both local and international clients.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-5eb011e e-flex e-con-boxed e-con e-parent optml-bg-lazyloaded e-lazyloaded\" data-id=\"5eb011e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n<div class=\"e-con-inner\">\n<div class=\"elementor-element elementor-element-e5b1b6b e-con-full e-flex e-con e-child\" data-id=\"e5b1b6b\" data-element_type=\"container\" data-e-type=\"container\">\u00a0<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-p8s6v39gf elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"p8s6v39gf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-gimxc9n1k e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"gimxc9n1k\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9bq2t398o e-con-full e-flex e-con e-child\" data-id=\"9bq2t398o\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-xuiuq08cj e-con-full e-flex e-con e-child\" data-id=\"xuiuq08cj\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8hjxr0v29 e-con-full e-flex e-con e-child\" data-id=\"8hjxr0v29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-zwwpg36d3 elementor-widget elementor-widget-heading\" data-id=\"zwwpg36d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Premier Choice for Luxury and Commercial Real Estate: Hisarkaya Real Estate<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-sfmwh3493 elementor-widget elementor-widget-text-editor\" data-id=\"sfmwh3493\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-69ef86ee-337c-832f-92da-0b11c2ed4ace-2\" data-testid=\"conversation-turn-46\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"8ead980f-61e0-4631-b919-d5650f34b81c\" data-message-model-slug=\"gpt-5-5-thinking\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word dark markdown-new-styling\">\n<p data-start=\"0\" data-end=\"336\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"0\" data-end=\"336\" data-is-last-node=\"\" data-is-only-node=\"\">With market-leading expertise and an outstanding track record in sales, we carry our legacy of knowledge and experience into the future. We are proud to hold a leading position in the luxury real estate and investment sector. Experience our exceptional service and expert guidance, shaped by our unwavering commitment to excellence.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\">\u00a0<\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\">\u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<div class=\"pointer-events-none -mt-px h-px translate-y-[calc(var(--scroll-root-safe-area-inset-bottom)-14*var(--spacing))]\" aria-hidden=\"true\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-rtm9w4b12 e-con-full e-flex e-con e-child\" data-id=\"rtm9w4b12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-vana69wa1 elementor-widget elementor-widget-image\" data-id=\"vana69wa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/elementor\/thumbs\/106cab36-c077-4653-89bb-a4ee2f547ab4-scaled-rmq0au0do9uy6w9nbnhjd0tno8aa6u9gcljmotzp6o.jpeg\" title=\"Active senior couple discussing with real estate agent over laptop in living room\" alt=\"Active senior couple discussing with real estate agent over laptop in living room\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de5d104 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"de5d104\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ffe80e\" data-id=\"7ffe80e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d5c6cb elementor-hidden-mobile elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"2d5c6cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-69e7f47 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69e7f47\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5b49b36\" data-id=\"5b49b36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-855b4c2 elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"855b4c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">An Exclusive Collection of Luxury Properties<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">Each property in our constantly updated and extensive portfolio represents the very best in luxury living and real estate investment opportunities. Explore our exclusive listings, offering distinctive features and premium amenities...<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fc62e9 elementor-widget elementor-widget-houzez_elementor_property-card-v5\" data-id=\"5fc62e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_property-card-v5.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div id=\"properties_module_section\" class=\"property-cards-module property-cards-module-v5 property-cards-module-col-3\">\n        <div id=\"module_properties\" class=\"listing-view grid-view row row-cols-1 row-cols-md-2 row-cols-lg-3 gy-4 gx-4\">\n            <div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20798\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1608_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1609_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1609_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1609_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1609_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1623_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1623_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1623_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1623_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1621_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1621_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1621_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1621_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1619_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1619_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1619_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1619_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1622_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1622_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1622_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1622_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1625_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1625_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1625_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1625_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1626_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1626_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1626_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1626_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1620_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1620_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1620_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1620_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20798\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20798\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20798 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20798\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/prime-investment-opportunity-in-the-heart-of-fethiye-brand-new-11-garden-apartment-for-sale-in-tuzla\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1608_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/prime-investment-opportunity-in-the-heart-of-fethiye-brand-new-11-garden-apartment-for-sale-in-tuzla\/\" role=\"link\">Prime Investment Opportunity in the Heart of Fethiye: Brand New 1+1 Garden Apartment for Sale in Tuzla<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $149,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tApartment\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yatak:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathroom:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">50<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"19672\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1134_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1135_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1135_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1135_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1135_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1136_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1136_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1136_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1136_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1137_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1137_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1137_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1137_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1138_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1138_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1138_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1138_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1139_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1139_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1139_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1139_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1140_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1140_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1140_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1140_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1141_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1141_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1141_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1141_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1142_result-584x438.webp&quot;,&quot;alt&quot;:&quot;2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1142_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1142_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1142_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"19672\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"19672\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-19672 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"19672\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/21-apartment-with-pool-in-a-perfect-complex-in-fethiye-ovacik\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\u0130YE OVACIK\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1134_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/21-apartment-with-pool-in-a-perfect-complex-in-fethiye-ovacik\/\" role=\"link\">2+1 APARTMENT WITH POOL IN A PERFECT COMPLEX IN FETH\u0130YE OVACIK<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $166,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tApartment\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">2<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">2<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">85<\/span> <span class=\"hz-figure area_postfix\">sq<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20630\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1703_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1703_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1703_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1703_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1701_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1701_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1701_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1701_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1671_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1671_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1671_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1671_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1672_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1672_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1672_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1672_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1673_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1673_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1673_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1673_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1674_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1674_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1674_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1674_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1675_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1675_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1675_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1675_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1676_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1676_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1676_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1676_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\\u015f \\u2013 Prime Location&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1677_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20630\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20630\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20630 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20630\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/modern-21-garden-floor-apartment-for-sale-in-fethiye-deliktas-prime-location\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\u015f \u2013 Prime Location\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1677_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/modern-21-garden-floor-apartment-for-sale-in-fethiye-deliktas-prime-location\/\" role=\"link\">Modern 2+1 Garden Floor Apartment for Sale in Fethiye Delikta\u015f \u2013 Prime Location<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $174,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tApartment\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">2<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathroom:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">68<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20909\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1381_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1381_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1381_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1381_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1382_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1382_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1382_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1382_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1383_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1383_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1383_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1383_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1384_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1384_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1384_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1384_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1385_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1385_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1385_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1385_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1386_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1386_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1386_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1386_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1387_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1387_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1387_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1387_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1388_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1388_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1388_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1388_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1389_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1389_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1389_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1389_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20909\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20909\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20909 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20909\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/sophisticated-41-luxury-smart-villa-in-yesiluzumlu\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_135626_0779_1777460161209_photo-2_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/sophisticated-41-luxury-smart-villa-in-yesiluzumlu\/\" role=\"link\">Sophisticated 4+1 Luxury Smart Villa in Yesiluzumlu<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $445,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">300<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"19888\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006582-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006582-2_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006582-2_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006582-2_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-3_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-3_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-3_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-3_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-4_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-4_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-4_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006593-4_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006608-2_result-2-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006608-2_result-2-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006608-2_result-2-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006608-2_result-2.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006634-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006634-2_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006634-2_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0006634-2_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008238-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008241-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008241-2_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008241-2_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008241-2_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008242-2_result-1-584x438.webp&quot;,&quot;alt&quot;:&quot;4+1 DETACHED VILLA IN 580 m\\u00b2 LAND IN FETH\\u0130YE OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008242-2_result-1-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008242-2_result-1-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/B0008242-2_result-1.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"19888\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"19888\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-19888 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"19888\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/41-detached-villa-in-580-m%c2%b2-land-in-fethiye-ovacik\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"4+1 DETACHED VILLA IN 580 m\u00b2 LAND IN FETH\u0130YE OVACIK\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260424_103024_0717_1777016247938_photo_result-1.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/41-detached-villa-in-580-m%c2%b2-land-in-fethiye-ovacik\/\" role=\"link\">4+1 DETACHED VILLA IN 580 m\u00b2 LAND IN FETH\u0130YE OVACIK<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $500,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garages:<\/span> <span class=\"hz-figure\">2<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">396<\/span> <span class=\"hz-figure area_postfix\">sq<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20080\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.42-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.42-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.46_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.43_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.45-1_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.37-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.47_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.48-1_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.37-3_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-21-at-11.38.37-4_result-584x438.webp&quot;,&quot;alt&quot;:&quot;LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20080\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20080\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20080 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20080\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-21-at-11.38.42-2_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-outdoor-indoor-pool-villa-in-ovacik\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-21-at-11.38.42-2_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-outdoor-indoor-pool-villa-in-ovacik\/\" role=\"link\">LUXURY OUTDOOR-INDOOR POOL VILLA IN OVACIK<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $555,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">230<\/span> <span class=\"hz-figure area_postfix\">sq<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20126\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121354_0732_1777654914438_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121354_0732_1777654914438_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121402_0733_1777654914221_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121402_0733_1777654914221_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121402_0733_1777654914221_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121402_0733_1777654914221_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121426_0734_1777654913868_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121426_0734_1777654913868_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121426_0734_1777654913868_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121426_0734_1777654913868_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121504_0735_1777654913503_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121504_0735_1777654913503_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121504_0735_1777654913503_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121504_0735_1777654913503_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121704_0739_1777654911740_photo_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121704_0739_1777654911740_photo_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121704_0739_1777654911740_photo_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dji_fly_20260429_121704_0739_1777654911740_photo_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1267_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1267_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1267_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1267_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1268_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1268_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1268_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1268_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1269_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1269_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1269_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1269_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1270_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1270_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1270_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1270_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1271_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Detached Villa with Private Garden, Pool &amp; Fully Furnished!&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1271_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1271_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1271_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20126\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20126\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20126 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20126\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/detached-villa-with-private-garden-pool-fully-furnished\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Detached Villa with Private Garden, Pool &amp; Fully Furnished!\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/dji_fly_20260429_121354_0732_1777654914438_photo_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/detached-villa-with-private-garden-pool-fully-furnished\/\" role=\"link\">Detached Villa with Private Garden, Pool &amp; Fully Furnished!<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $675,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">200<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20404\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1646_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1647_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1647_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1647_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1647_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1648_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1648_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1648_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1648_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1649_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1649_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1649_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1649_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1650_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1650_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1650_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1650_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1651_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1651_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1651_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1651_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1652_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1652_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1652_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1652_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1653_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1653_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1653_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1653_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1654_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Exclusive Living in Babata\\u015f\\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1654_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1654_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_1654_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20404\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20404\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20404 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20404\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/exclusive-living-in-babatasi-fethiye-corner-plot-modern-architecture-customizable-41-luxury-villa\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Exclusive Living in Babata\u015f\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_1646_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/exclusive-living-in-babatasi-fethiye-corner-plot-modern-architecture-customizable-41-luxury-villa\/\" role=\"link\">Exclusive Living in Babata\u015f\u0131, Fethiye: Corner Plot, Modern Architecture &amp; Customizable 4+1 Luxury Villa<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $740,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">4<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">210<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"item-listing-wrap hz-item-gallery-js item-wrap-v5 hz-map-trigger\" data-hz-id=\"20548\" data-images=\"[{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3287-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3287-2_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3287-2_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3287-2_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3288_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289-2_result-584x438.webp 584w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289-2_result-1536x1152.webp 1536w, https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3289-2_result.webp 1600w&quot;,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3292-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3295-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3290-2_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3291_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3292_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;},{&quot;image&quot;:&quot;https:\\\/\\\/hisarkayaemlak.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_3293_result-584x438.webp&quot;,&quot;alt&quot;:&quot;Luxury 3+1 Villa for Sale in Ovac\\u0131k, Fethiye \\u2013 Rental Guarantee &amp; Private Concept&quot;,&quot;width&quot;:584,&quot;height&quot;:438,&quot;srcset&quot;:false,&quot;sizes&quot;:&quot;(max-width: 584px) 100vw, 584px&quot;}]\">\n\t<div class=\"item-wrap h-100\">\n\t\t<div class=\"d-flex flex-column align-items-center h-100\">\n\t\t\t<div class=\"item-header\">\n\t\t\t\t<span class=\"label-featured label me-1\" role=\"status\">Featured<\/span>\t\t\t\t<div class=\"labels-wrap d-flex align-items-center gap-1\" role=\"group\"> \n\n\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/for-sale\/\" class=\"label-status label status-color-241\">\n\t\t\t\t\tFOR SALE\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/best-deals\/\" class=\"hz-label label label-color-225\">\n\t\t\t\t\tBest Deals\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-rent\/\" class=\"hz-label label label-color-336\">\n\t\t\t\t\tFor Rent\n\t\t\t\t<\/a><a href=\"https:\/\/hisarkayaemlak.com\/en\/etiket\/for-sale\/\" class=\"hz-label label label-color-228\">\n\t\t\t\t\tFor Sale\n\t\t\t\t<\/a>       \n\n<\/div>\n\t\t\t\t<ul class=\"item-tools d-flex align-items-center justify-content-center gap-1\">\n        <li class=\"item-tool item-preview\">\n        <span class=\"hz-show-lightbox-js item-tool-preview text-center\" data-listid=\"20548\">\n            <span data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"\u00d6nizleme\">\n                <i class=\"houzez-icon icon-expand-3\"><\/i>   \n            <\/span>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n        \n        <li class=\"item-tool item-favorite\">\n        <span class=\"add-favorite-js item-tool-favorite text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Favori\" data-listid=\"20548\">\n            <i class=\"houzez-icon icon-love-it \"><\/i>\n        <\/span><!-- item-tool-favorite -->\n    <\/li><!-- item-tool -->\n    \n        <li class=\"item-tool item-compare\">\n        <span class=\"houzez_compare compare-20548 item-tool-compare text-center\" data-bs-toggle=\"tooltip\" data-bs-placement=\"top\" title=\"Add Comparison\" data-listing_id=\"20548\" data-listing_image=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result-584x438.webp\">\n            <i class=\"houzez-icon icon-add-circle\"><\/i>\n            <!-- <i class=\"houzez-icon icon-subtract-circle\"><\/i> -->\n        <\/span><!-- item-tool-compare -->\n    <\/li><!-- item-tool -->\n    <\/ul><!-- item-tools -->\n\t\t\t\t<div class=\"listing-image-wrap\">\n\t<div class=\"listing-thumb\">\n\t\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-31-villa-for-sale-in-ovacik-fethiye-rental-guarantee-private-concept\/\" class=\"listing-featured-thumb hover-effect image-wrap\" role=\"link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"438\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result-584x438.webp\" class=\"img-fluid wp-post-image\" alt=\"Luxury 3+1 Villa for Sale in Ovac\u0131k, Fethiye \u2013 Rental Guarantee &amp; Private Concept\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result-584x438.webp 584w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result-1536x1152.webp 1536w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/05\/IMG_3289_result.webp 1600w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/>\t\t<\/a><!-- hover-effect -->\n\t<\/div>\n<\/div>\t\t\t\t<div class=\"preview_loader\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"item-body w-100 d-flex flex-column flex-fill align-items-center\">\n\t\t\t\t<h2 class=\"item-title mb-2 \">\n\t<a target=\"_self\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-31-villa-for-sale-in-ovacik-fethiye-rental-guarantee-private-concept\/\" role=\"link\">Luxury 3+1 Villa for Sale in Ovac\u0131k, Fethiye \u2013 Rental Guarantee &amp; Private Concept<\/a>\n<\/h2><!-- item-title -->\t\t\t\t<div class=\"item-v5-price mb-1\">\n\t\t\t\t\t $750,000\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"item-v5-type d-flex flex-grow-1 text-center mb-3\">\n\t\t\t\t\tVilla\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<ul class=\"item-amenities item-amenities-with-icons d-flex flex-wrap align-items-center gap-2 justify-content-center\" role=\"list\">\n\t<li class=\"h-beds d-flex align-items-center me-1\"><i class=\"houzez-icon icon-hotel-double-bed-1 me-2\"><\/i><span class=\"item-amenities-text\">Yataklar:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-baths d-flex align-items-center me-1\"><i class=\"houzez-icon icon-bathroom-shower-1 me-2\"><\/i><span class=\"item-amenities-text\">Bathrooms:<\/span> <span class=\"hz-figure\">3<\/span><\/li><li class=\"h-cars d-flex align-items-center me-1\"><i class=\"houzez-icon icon-car-1 me-2\"><\/i><span class=\"item-amenities-text\">Garage:<\/span> <span class=\"hz-figure\">1<\/span><\/li><li class=\"h-area d-flex align-items-center me-1\"><i class=\"houzez-icon icon-ruler-triangle me-2\"><\/i><span class=\"hz-figure me-1\">280<\/span> <span class=\"hz-figure area_postfix\">sqm<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>        <\/div><!-- listing-view -->\n\n            <\/div><!-- property-grid-module -->\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86b9f70 elementor-hidden-mobile elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"86b9f70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e23522a elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e23522a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-422dc65\" data-id=\"422dc65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c7be67 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"9c7be67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-r0oqkydgu elementor-section-content-bottom elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"r0oqkydgu\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d7f8tgqi\" data-id=\"7d7f8tgqi\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-otagzualc elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"otagzualc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-54rfe1for elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"54rfe1for\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-deoyboqw6\" data-id=\"deoyboqw6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35k6z10vh animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"35k6z10vh\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Why Choose Hisarkaya Real Estate?<\/h2>\n                \n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-nq6vemcx9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"nq6vemcx9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-qy5g6mga3 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"qy5g6mga3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">01.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1p995d62p animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"1p995d62p\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Years of Expertise in Fethiye and the Surrounding Region<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">We know every neighbourhood and every street across Fethiye, \u00d6l\u00fcdeniz, G\u00f6cek, Ka\u015f, and the surrounding areas. With our in-depth knowledge of the local market, we offer you more than just listings \u2014 we present genuine opportunities.<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-zyrd0zrto elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"zyrd0zrto\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dd2tx7hjt\" data-id=\"dd2tx7hjt\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-jhujj0379 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"jhujj0379\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">02.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-hoxej6rbw animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"hoxej6rbw\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">A Transparent and Trusted Process from Start to Finish<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">From title deed checks and contract procedures to official transactions and final handover, we guide you through every step of the process. You are never left alone at any stage.<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bu252hyc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3bu252hyc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ecs7pjys animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6ecs7pjys\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">03.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-n1fsbow9s animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"n1fsbow9s\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Complete Support for Local and International Buyers<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">We provide services in Turkish, English, Arabic, and Russian. We also offer dedicated consultancy for international buyers on Turkish citizenship applications, title deed procedures, and property management.\n<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55sfab8qi elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"55sfab8qi\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-x8f5b2c4m\" data-id=\"x8f5b2c4m\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-xm08f2xyn animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"xm08f2xyn\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                \n                                    <p class=\"houzez_section_subtitle\">Contact Us for Your Exclusive Property Search<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-czklf271f elementor-button-align-stretch elementor-widget elementor-widget-houzez_elementor_inquiry_form\" data-id=\"czklf271f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_inquiry_form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <script type=\"application\/javascript\">\n            jQuery(document).bind(\"ready\", function () {\n                houzezValidateElementor(\"#houzez-form-czklf271f\" );\n            });\n        <\/script>\n\n\n        <form class=\"elementor-form houzez-ele-form-js\" id=\"houzez-form-czklf271f\" method=\"post\" name=\"New Form\" action=\"https:\/\/hisarkayaemlak.com\/wp-admin\/admin-ajax.php\">\n            <input type=\"hidden\" name=\"form_id\" value=\"czklf271f\"\/>\n            <input type=\"hidden\" name=\"action\" value=\"houzez_ele_inquiry_form\" \/>\n            <input type=\"hidden\" name=\"source_link\" value=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk\/luxury-31-villa-for-sale-in-ovacik-fethiye-rental-guarantee-private-concept\/\" \/>\n            <input type=\"hidden\" name=\"lead_page_id\" value=\"20548\" \/>\n            <input type=\"hidden\" name=\"is_estimation\" value=\"yes\" \/>\n            <input type=\"hidden\" name=\"webhook\" value=\"false\" \/>\n            <input type=\"hidden\" name=\"webhook_url\" value=\"\" \/>\n            <input type=\"hidden\" name=\"redirect_to\" value=\"\" \/>\n            <input type=\"hidden\" name=\"email_subject\" value=\"New message from &quot;Houzez 01&quot;\" \/>\n            <input type=\"hidden\" name=\"google_recaptcha\" value=\"yes\" \/>\n\n            <div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\n                                    <div class=\"elementor-field-group elementor-column form-group elementor-field-group-b7fe77d elementor-col-100 elementor-field-required\">\n                    <label for=\"form-field-b7fe77d\" class=\"form-label elementor-field-label\">Information<\/label>        <div class=\"elementor-field elementor-select-wrapper\">\n            <select name=\"user_type\" id=\"form-field-b7fe77d\" class=\"elementor-field-textual form-control elementor-size-md\" required=\"required\" title=\"* Information\">\n                <option value=\"\">Select<\/option><option value=\"I\u2019m Looking to Rent\">I\u2019m Looking to Rent<\/option><option value=\"I\u2019m Looking to Buy\">I\u2019m Looking to Buy<\/option>            <\/select>\n        <\/div>\n                            <\/div>\n\n                                        <div class=\"elementor-field-group elementor-column form-group elementor-field-group-cc6b92f elementor-col-50 elementor-field-required\">\n                    <label for=\"form-field-cc6b92f\" class=\"form-label elementor-field-label\">First Name<\/label><input type=\"text\" name=\"first_name\" id=\"form-field-cc6b92f\" class=\"elementor-field form-control elementor-size-md elementor-field-textual\" placeholder=\"First Name\" title=\"* First Name\" required=\"required\">                    <\/div>\n\n                                        <div class=\"elementor-field-group elementor-column form-group elementor-field-group-3cc124e elementor-col-50\">\n                    <label for=\"form-field-3cc124e\" class=\"form-label elementor-field-label\">Last Name<\/label><input type=\"text\" name=\"last_name\" id=\"form-field-3cc124e\" class=\"elementor-field form-control elementor-size-md elementor-field-textual\" placeholder=\"Last Name\" title=\"* Last Name\">                    <\/div>\n\n                                        <div class=\"elementor-field-group elementor-column form-group elementor-field-group-932d82c elementor-col-100 elementor-field-required\">\n                    <label for=\"form-field-932d82c\" class=\"form-label elementor-field-label\">Email Address<\/label><input type=\"email\" name=\"email\" id=\"form-field-932d82c\" class=\"elementor-field form-control elementor-size-md elementor-field-textual\" placeholder=\"Email Address\" title=\"* Email Address\" required=\"required\">                    <\/div>\n\n                                        <div class=\"elementor-field-group elementor-column form-group elementor-field-group-2eaf20d elementor-col-50 elementor-field-required\">\n                    <label for=\"form-field-2eaf20d\" class=\"form-label elementor-field-label\">Location<\/label>        <div class=\"elementor-field elementor-select-wrapper\">\n            <select name=\"e_meta[city]\" id=\"form-field-2eaf20d\" class=\"elementor-field-textual form-control elementor-size-md\" required=\"required\" title=\"* Location\">\n                <option value=\"\">Select<\/option><option data-ref=\"fethiye\" data-belong=\"\" value=\"fethiye\"> FETH\u0130YE<\/option><option data-ref=\"calis-neighbourhood\" data-belong=\"\" value=\"calis-neighbourhood\">-  \u00c7al\u0131\u015f (Neighbourhood)<\/option><option data-ref=\"faralya-neighbourhood\" data-belong=\"\" value=\"faralya-neighbourhood\">-  Faralya (Neighbourhood)<\/option><option data-ref=\"fethiye-city-centre-neighbourhood\" data-belong=\"\" value=\"fethiye-city-centre-neighbourhood\">-  Fethiye City Centre (Neighbourhood)<\/option><option data-ref=\"gocek-neighbourhood\" data-belong=\"\" value=\"gocek-neighbourhood\">-  G\u00f6cek (Neighbourhood)<\/option><option data-ref=\"karagozler-neighbourhood\" data-belong=\"\" value=\"karagozler-neighbourhood\">-  Karag\u00f6zler (Neighbourhood)<\/option><option data-ref=\"kayakoy-neighbourhood\" data-belong=\"\" value=\"kayakoy-neighbourhood\">-  Kayak\u00f6y (Neighbourhood)<\/option><option data-ref=\"oludeniz-neighbourhood\" data-belong=\"\" value=\"oludeniz-neighbourhood\">-  \u00d6l\u00fcdeniz (Neighbourhood)<\/option><option data-ref=\"ovacik-neighbourhood\" data-belong=\"\" value=\"ovacik-neighbourhood\">-  Ovac\u0131k (Neighbourhood)<\/option><option data-ref=\"sovalye-adasi-neighbourhood\" data-belong=\"\" value=\"sovalye-adasi-neighbourhood\">-  \u015e\u00f6valye Adas\u0131 (Neighbourhood)<\/option><option data-ref=\"tasyaka-neighbourhood\" data-belong=\"\" value=\"tasyaka-neighbourhood\">-  Ta\u015fyaka (Neighbourhood)<\/option><option data-ref=\"yesiluzumlu-neighbourhood\" data-belong=\"\" value=\"yesiluzumlu-neighbourhood\">-  Ye\u015fil\u00fcz\u00fcml\u00fc (Neighbourhood)<\/option><option data-ref=\"istanbul\" data-belong=\"\" value=\"istanbul\"> \u0130stanbul<\/option><option data-ref=\"kalkan-district-neighbourhood\" data-belong=\"\" value=\"kalkan-district-neighbourhood\"> Kalkan (District \/ Neighbourhood)<\/option><option data-ref=\"kas-district\" data-belong=\"\" value=\"kas-district\"> Ka\u015f (District)<\/option><option data-ref=\"mugla\" data-belong=\"\" value=\"mugla\"> MU\u011eLA<\/option><option data-ref=\"seydikemer-district\" data-belong=\"\" value=\"seydikemer-district\"> SEYD\u0130KEMER (District)<\/option>            <\/select>\n        <\/div>\n                            <\/div>\n\n                                        <div class=\"elementor-field-group elementor-column form-group elementor-field-group-f0ee6fc elementor-col-50 elementor-field-required\">\n                    <label for=\"form-field-f0ee6fc\" class=\"form-label elementor-field-label\">&nbsp;<\/label><input type=\"text\" name=\"e_meta[zipcode]\" id=\"form-field-f0ee6fc\" class=\"elementor-field form-control elementor-size-md elementor-field-textual\" placeholder=\"Zip Code\" title=\"* Zip Code\" required=\"required\">                    <\/div>\n\n                                        <div class=\"elementor-field-group elementor-column form-group elementor-field-group-3180222 elementor-col-100 elementor-field-required\">\n                    <label for=\"form-field-3180222\" class=\"form-label elementor-field-label\">Property<\/label>        <div class=\"elementor-field elementor-select-wrapper\">\n            <select name=\"e_meta[property_type]\" id=\"form-field-3180222\" class=\"elementor-field-textual form-control elementor-size-md\" required=\"required\" title=\"* Property\">\n                <option value=\"\">Select a type<\/option><option value=\"villa\"> Villa<\/option><option value=\"apartment\"> Apartment<\/option><option value=\"commercial-real-estate\"> Commercial Real Estate<\/option><option value=\"entire-building\"> Entire Building<\/option><option value=\"land-plots\"> Land &amp; Plots<\/option><option value=\"off-plan-property\"> Off-Plan Property<\/option><option value=\"tourism-facility\"> Tourism Facility<\/option>            <\/select>\n        <\/div>\n                            <\/div>\n\n                    \n                    \n                                        <div class=\"form-group elementor-field-group elementor-col-100\">\n                        <label class=\"control control--checkbox m-0 \">\n                                                        <input required type=\"checkbox\" name=\"gdpr_agreement\" id=\"gdpr_agreement\" aria-required=\"true\">\n                            <span class=\"control__indicator\"><\/span>\n                                                        <div class=\"gdpr-text-wrap\">\n                            I consent to this website storing the information I have submitted.                            <\/div>\n                            \n                        <\/label>\n                    <\/div><!-- form-group -->\n                    \n                    \n                                        <div class=\"elementor-field-group\">\n                                            <\/div>\n                    \n                    <div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100\">\n                    <button type=\"submit\" class=\"houzez-submit-button houzez-contact-form-js elementor-button elementor-size-md\">\n                        <i class=\"houzez-loader-js houzez-hidden spinner-border spinner-border-sm\"><\/i>\n                                                    Send                                            <\/button>\n                <\/div>\n            <\/div><!-- End wrapper-->\n            <br\/>\n            <div class=\"ele-form-messages\"><\/div>\n            <div class=\"error-container\"><\/div>\n\n        <\/form>\n\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-niqhqv6ze elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"niqhqv6ze\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-k9lea72w5 e-flex e-con-boxed e-con e-parent\" data-id=\"k9lea72w5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aa99d53la e-con-full e-flex e-con e-child\" data-id=\"aa99d53la\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6w2ob72dt e-con-full e-flex e-con e-child\" data-id=\"6w2ob72dt\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1de4ddl59 e-con-full e-flex e-con e-child\" data-id=\"1de4ddl59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0h4b6r4dy elementor-widget elementor-widget-heading\" data-id=\"0h4b6r4dy\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Real Estate Blog &amp; News<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-hd8jxerhe e-con-full e-flex e-con e-child\" data-id=\"hd8jxerhe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52t1zu6lb elementor-widget elementor-widget-houzez_elementor_blog_posts_v2\" data-id=\"52t1zu6lb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_blog_posts_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"blog-posts-module blog-posts-module-v3\">\n            <div class=\"row\">\n                <div class=\"col-md-5 col-12\"><div class=\"blog-posts-module-v3-left-wrap\"><div id=\"post-19423\" class=\"blog-post-item blog-post-item-v3 mb-3 post-19423 post type-post status-publish format-standard has-post-thumbnail hentry category-information\">\n\t\t<div class=\"blog-post-thumb\">\n\t\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/fethiyes-most-sought-after-neighbourhoods-where-should-you-invest\/\" class=\"hover-effect image-wrap\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1200\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A6832_result.webp\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A6832_result.webp 1920w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A6832_result-1536x960.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/a>\n\t<\/div><!-- blog-post-thumb -->\n\t\n\t<div class=\"blog-post-content-wrap p-4\">\n\t\t<div class=\"blog-post-meta\">\n\t\t\t<ul class=\"list-inline\">\n\t\t\t\t\t\t\t\t<li class=\"list-inline-item\">\n\t\t\t\t\t<time datetime=\"May 2, 2026\"><i class=\"houzez-icon icon-calendar-3 me-1\"><\/i> May 2, 2026<\/time>\n\t\t\t\t<\/li>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<li class=\"list-inline-item\">\n\t\t\t\t\t<i class=\"houzez-icon icon-tags me-1\"><\/i> <a href=\"https:\/\/hisarkayaemlak.com\/en\/category\/information\/\" rel=\"category tag\">Information<\/a>\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div><!-- blog-post-meta -->\n\t\t<div class=\"blog-post-title\">\n\t\t\t<h3><a href=\"https:\/\/hisarkayaemlak.com\/en\/fethiyes-most-sought-after-neighbourhoods-where-should-you-invest\/\">Fethiye\u2019s Most Sought-After Neighbourhoods: Where Should You Invest?<\/a><\/h3>\n\t\t<\/div><!-- blog-post-title -->\n\t\t<div class=\"blog-post-body\">\n\t\t\tIf you are considering a real estate investment in Fethiye, choosing the right neighbourhood will directly influence your returns. Here is a brief. <a class=\"continue-reading\" href=\"https:\/\/hisarkayaemlak.com\/en\/fethiyes-most-sought-after-neighbourhoods-where-should-you-invest\/\">Continue reading <i class=\"fa fa-angle-double-right\"><\/i><\/a>\t\t<\/div><!-- blog-post-body -->\n\t<\/div><!-- blog-post-content-wrap -->\n<\/div><!-- blog-post-item -->\n<\/div><\/div><div class=\"col-md-7 col-12\"><div class=\"blog-posts-module-v3-right-wrap\"><div id=\"post-18878\" class=\"blog-post-item blog-post-item-v3 d-flex align-items-stretch mb-3 post-18878 post type-post status-publish format-standard has-post-thumbnail hentry category-information\">\n\t\t<div class=\"blog-post-thumb d-flex align-items-center h-100\">\n\t\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/how-can-foreigners-buy-property-in-turkey-legal-process-and-key-considerations\/\" class=\"hover-effect image-wrap\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1200\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A6854_result.webp\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A6854_result.webp 1920w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A6854_result-1536x960.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/a>\n\t<\/div><!-- blog-post-thumb -->\n\t\n\t<div class=\"blog-post-content-wrap d-flex flex-column justify-content-center p-4\">\n\t\t<div class=\"blog-post-title\">\n\t\t\t<h3 class=\"mb-1\"><a href=\"https:\/\/hisarkayaemlak.com\/en\/how-can-foreigners-buy-property-in-turkey-legal-process-and-key-considerations\/\">How Can Foreigners Buy Property in Turkey? Legal Process and Key Considerations<\/a><\/h3>\n\t\t<\/div><!-- blog-post-title -->\n\t\t<div class=\"blog-post-meta small\">\n\t\t\t<ul class=\"list-inline d-flex align-items-center mb-1\">\n\t\t\t\t\t\t\t\t<li class=\"list-inline-item\">\n\t\t\t\t\t<time datetime=\"May 2, 2026\"><i class=\"houzez-icon icon-calendar-3 me-1\"><\/i> May 2, 2026<\/time>\n\t\t\t\t<\/li>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<li class=\"list-inline-item\">\n\t\t\t\t\t<i class=\"houzez-icon icon-tags me-1\"><\/i> <a href=\"https:\/\/hisarkayaemlak.com\/en\/category\/information\/\" rel=\"category tag\">Information<\/a>\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div><!-- blog-post-meta -->\n\t\t<div class=\"blog-post-body mb-1\">\n\t\t\tThe process of foreign nationals acquiring real estate in Turkey has been significantly simplified...\t\t<\/div><!-- blog-post-body -->\n\t<\/div><!-- blog-post-content-wrap -->\n<\/div><!-- blog-post-item -->\n<div id=\"post-18876\" class=\"blog-post-item blog-post-item-v3 d-flex align-items-stretch mb-3 post-18876 post type-post status-publish format-standard has-post-thumbnail hentry category-information\">\n\t\t<div class=\"blog-post-thumb d-flex align-items-center h-100\">\n\t\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/real-estate-investment-for-turkish-citizenship-a-step-by-step-guide\/\" class=\"hover-effect image-wrap\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1200\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A7075_result.webp\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A7075_result.webp 1920w, https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/0B0A7075_result-1536x960.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/a>\n\t<\/div><!-- blog-post-thumb -->\n\t\n\t<div class=\"blog-post-content-wrap d-flex flex-column justify-content-center p-4\">\n\t\t<div class=\"blog-post-title\">\n\t\t\t<h3 class=\"mb-1\"><a href=\"https:\/\/hisarkayaemlak.com\/en\/real-estate-investment-for-turkish-citizenship-a-step-by-step-guide\/\">Real Estate Investment for Turkish Citizenship: A Step-by-Step Guide<\/a><\/h3>\n\t\t<\/div><!-- blog-post-title -->\n\t\t<div class=\"blog-post-meta small\">\n\t\t\t<ul class=\"list-inline d-flex align-items-center mb-1\">\n\t\t\t\t\t\t\t\t<li class=\"list-inline-item\">\n\t\t\t\t\t<time datetime=\"May 2, 2026\"><i class=\"houzez-icon icon-calendar-3 me-1\"><\/i> May 2, 2026<\/time>\n\t\t\t\t<\/li>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<li class=\"list-inline-item\">\n\t\t\t\t\t<i class=\"houzez-icon icon-tags me-1\"><\/i> <a href=\"https:\/\/hisarkayaemlak.com\/en\/category\/information\/\" rel=\"category tag\">Information<\/a>\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div><!-- blog-post-meta -->\n\t\t<div class=\"blog-post-body mb-1\">\n\t\t\tTurkey is one of the few countries that grants citizenship rights to foreign nationals who make...\t\t<\/div><!-- blog-post-body -->\n\t<\/div><!-- blog-post-content-wrap -->\n<\/div><!-- blog-post-item -->\n<div id=\"post-18874\" class=\"blog-post-item blog-post-item-v3 d-flex align-items-stretch mb-3 post-18874 post type-post status-publish format-standard has-post-thumbnail hentry category-information\">\n\t\t<div class=\"blog-post-thumb d-flex align-items-center h-100\">\n\t\t<a href=\"https:\/\/hisarkayaemlak.com\/en\/buying-a-home-in-fethiye-everything-you-need-to-know-in-2025\/\" class=\"hover-effect image-wrap\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1344\" height=\"768\" src=\"https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/MYGLABANNER.webp\" class=\"img-fluid wp-post-image\" alt=\"\" \/>\t\t<\/a>\n\t<\/div><!-- blog-post-thumb -->\n\t\n\t<div class=\"blog-post-content-wrap d-flex flex-column justify-content-center p-4\">\n\t\t<div class=\"blog-post-title\">\n\t\t\t<h3 class=\"mb-1\"><a href=\"https:\/\/hisarkayaemlak.com\/en\/buying-a-home-in-fethiye-everything-you-need-to-know-in-2025\/\">Buying a Home in Fethiye: Everything You Need to Know in 2025<\/a><\/h3>\n\t\t<\/div><!-- blog-post-title -->\n\t\t<div class=\"blog-post-meta small\">\n\t\t\t<ul class=\"list-inline d-flex align-items-center mb-1\">\n\t\t\t\t\t\t\t\t<li class=\"list-inline-item\">\n\t\t\t\t\t<time datetime=\"May 2, 2026\"><i class=\"houzez-icon icon-calendar-3 me-1\"><\/i> May 2, 2026<\/time>\n\t\t\t\t<\/li>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<li class=\"list-inline-item\">\n\t\t\t\t\t<i class=\"houzez-icon icon-tags me-1\"><\/i> <a href=\"https:\/\/hisarkayaemlak.com\/en\/category\/information\/\" rel=\"category tag\">Information<\/a>\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div><!-- blog-post-meta -->\n\t\t<div class=\"blog-post-body mb-1\">\n\t\t\tFethiye, one of Turkey's most popular holiday and living destinations, has become one of the most...\t\t<\/div><!-- blog-post-body -->\n\t<\/div><!-- blog-post-content-wrap -->\n<\/div><!-- blog-post-item -->\n<\/div><\/div>            <\/div><!-- row -->\n        <\/div><!-- blog-posts-module -->\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-g19y8uus7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"g19y8uus7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-k39ahwjrf\" data-id=\"k39ahwjrf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-nxxrtesjj elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"nxxrtesjj\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-pf7viohi6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"pf7viohi6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fghisptks\" data-id=\"fghisptks\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0218lh0k elementor-widget elementor-widget-heading\" data-id=\"b0218lh0k\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PORTFOLIOS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-vtja3e7dn elementor-widget elementor-widget-Houzez_Taxonomies_Grids_Carousel\" data-id=\"vtja3e7dn\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Houzez_Taxonomies_Grids_Carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div id=\"houzez-carousel-dPMH8\" data-token=\"dPMH8\" class=\"taxonomy-grids-module taxonomy-grids-module-v5-slider houzez-carousel-js houzez-all-slider-wrap houzez-carousel-nav houzez-carousel-arrows-dPMH8 taxonomy-grids-module-v5-6cols\">\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-item-wrap h-100\">\r\n\t\t\t\t\t<div class=\"taxonomy-item\" style=\"background-image: url(https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/villalar-AdobeStock_99044380-scaled-1-780x780.webp);\">\r\n\t\t\t\t\t\t<a class=\"taxonomy-link hover-effect-flat\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk%20t\u00fcr\u00fc\/villa\/\">\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-text-wrap d-flex flex-column justify-content-end align-items-start h-100 w-100\">\r\n\t\t\t\t\t\t\t\t<div class=\"taxonomy-title\">Villa<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"taxonomy-subtitle\">\r\n\t\t\t\t\t\t\t\t\t8 \r\n\t\t\t\t\t\t\t\t\tANNOUNCEMENTS\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- taxonomy-text-wrap -->\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-item-wrap h-100\">\r\n\t\t\t\t\t<div class=\"taxonomy-item\" style=\"background-image: url(https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/dairelerAdobeStock_295713811-scaled-1-780x780.webp);\">\r\n\t\t\t\t\t\t<a class=\"taxonomy-link hover-effect-flat\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk%20t\u00fcr\u00fc\/apartment\/\">\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-text-wrap d-flex flex-column justify-content-end align-items-start h-100 w-100\">\r\n\t\t\t\t\t\t\t\t<div class=\"taxonomy-title\">Apartment<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"taxonomy-subtitle\">\r\n\t\t\t\t\t\t\t\t\t3 \r\n\t\t\t\t\t\t\t\t\tANNOUNCEMENTS\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- taxonomy-text-wrap -->\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-item-wrap h-100\">\r\n\t\t\t\t\t<div class=\"taxonomy-item\" style=\"background-image: url(https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/komple-bina-AdobeStock_136883925-scaled-1-780x780.webp);\">\r\n\t\t\t\t\t\t<a class=\"taxonomy-link hover-effect-flat\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk%20t\u00fcr\u00fc\/entire-building\/\">\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-text-wrap d-flex flex-column justify-content-end align-items-start h-100 w-100\">\r\n\t\t\t\t\t\t\t\t<div class=\"taxonomy-title\">Entire Building<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"taxonomy-subtitle\">\r\n\t\t\t\t\t\t\t\t\t0 \r\n\t\t\t\t\t\t\t\t\tReal Estate\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- taxonomy-text-wrap -->\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-item-wrap h-100\">\r\n\t\t\t\t\t<div class=\"taxonomy-item\" style=\"background-image: url(https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/projeler-AdobeStock_166539969-scaled-1-780x780.webp);\">\r\n\t\t\t\t\t\t<a class=\"taxonomy-link hover-effect-flat\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk%20t\u00fcr\u00fc\/off-plan-property\/\">\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-text-wrap d-flex flex-column justify-content-end align-items-start h-100 w-100\">\r\n\t\t\t\t\t\t\t\t<div class=\"taxonomy-title\">Off-Plan Property<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"taxonomy-subtitle\">\r\n\t\t\t\t\t\t\t\t\t0 \r\n\t\t\t\t\t\t\t\t\tReal Estate\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- taxonomy-text-wrap -->\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-item-wrap h-100\">\r\n\t\t\t\t\t<div class=\"taxonomy-item\" style=\"background-image: url(https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/turistik-tesisAdobeStock_249890395-scaled-1-780x780.webp);\">\r\n\t\t\t\t\t\t<a class=\"taxonomy-link hover-effect-flat\" href=\"https:\/\/hisarkayaemlak.com\/en\/m\u00fclk%20t\u00fcr\u00fc\/tourism-facility\/\">\r\n\t\t\t\t\t\t\t<div class=\"taxonomy-text-wrap d-flex flex-column justify-content-end align-items-start h-100 w-100\">\r\n\t\t\t\t\t\t\t\t<div class=\"taxonomy-title\">Tourism Facility<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"taxonomy-subtitle\">\r\n\t\t\t\t\t\t\t\t\t0 \r\n\t\t\t\t\t\t\t\t\tReal Estate\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- taxonomy-text-wrap -->\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bbn9lai3 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"5bbn9lai3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ha2hx0uoo elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ha2hx0uoo\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-gnigovc25\" data-id=\"gnigovc25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-919e42f elementor-widget elementor-widget-heading\" data-id=\"919e42f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">DISCOVER CITIES<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-48d2fdb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"48d2fdb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-09bb90b\" data-id=\"09bb90b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f673fda animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"f673fda\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v3\" data-ratio=\"vertical\" style=\"background-image: url(https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/AdobeStock_732507589-scaled.webp)\">\n            <a class=\"grid-item-link hover-effect-flat\"  target=\"_blank\" href=\"https:\/\/hisarkayaemlak.com\/en\/%C5%9EEH%C4%B0R\/oludeniz-neighbourhood\/\">\n                <div class=\"grid-item-text-wrap d-flex flex-column justify-content-between w-100 h-100\">\n                    <div class=\"d-flex flex-column\">\n                        \n                                                <div class=\"grid-item-title\">\u00d6L\u00dcDEN\u0130Z<\/div>\n                                            <\/div>\n                    \n                                        <div class=\"d-flex align-items-center justify-content-between\">\n                        <div class=\"grid-item-text-link\">More details<\/div>\n                        <div class=\"grid-item-icon\">\n                            <i class=\"houzez-icon icon-arrow-button-right-2\"><\/i>\n                        <\/div>\n                    <\/div>\n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2ffa2d7\" data-id=\"2ffa2d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa5d5ed animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"aa5d5ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v3\" data-ratio=\"vertical\" style=\"background-image: url(https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/AdobeStock_231500578-scaled.jpeg)\">\n            <a class=\"grid-item-link hover-effect-flat\"  target=\"_blank\" href=\"https:\/\/hisarkayaemlak.com\/en\/%C5%9EEH%C4%B0R\/gocek-neighbourhood\/\">\n                <div class=\"grid-item-text-wrap d-flex flex-column justify-content-between w-100 h-100\">\n                    <div class=\"d-flex flex-column\">\n                        \n                                                <div class=\"grid-item-title\">G\u00d6CEK<\/div>\n                                            <\/div>\n                    \n                                        <div class=\"d-flex align-items-center justify-content-between\">\n                        <div class=\"grid-item-text-link\">More details<\/div>\n                        <div class=\"grid-item-icon\">\n                            <i class=\"houzez-icon icon-arrow-button-right-2\"><\/i>\n                        <\/div>\n                    <\/div>\n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b548608\" data-id=\"b548608\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b4f89d animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"1b4f89d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v3\" data-ratio=\"vertical\" style=\"background-image: url(https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/AdobeStock_325949423-scaled.webp)\">\n            <a class=\"grid-item-link hover-effect-flat\"  target=\"_blank\" href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/antalya\/\">\n                <div class=\"grid-item-text-wrap d-flex flex-column justify-content-between w-100 h-100\">\n                    <div class=\"d-flex flex-column\">\n                        \n                                                <div class=\"grid-item-title\">ANTALYA<\/div>\n                                            <\/div>\n                    \n                                        <div class=\"d-flex align-items-center justify-content-between\">\n                        <div class=\"grid-item-text-link\">More details<\/div>\n                        <div class=\"grid-item-icon\">\n                            <i class=\"houzez-icon icon-arrow-button-right-2\"><\/i>\n                        <\/div>\n                    <\/div>\n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9b3c4d8\" data-id=\"9b3c4d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe6260f animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"fe6260f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v3\" data-ratio=\"vertical\" style=\"background-image: url(https:\/\/hisarkayaemlak.com\/wp-content\/uploads\/2026\/04\/fkabay-body-of-water-3150734-scaled.webp)\">\n            <a class=\"grid-item-link hover-effect-flat\"  target=\"_blank\" href=\"https:\/\/hisarkayaemlak.com\/en\/durum\/fethiye\/\">\n                <div class=\"grid-item-text-wrap d-flex flex-column justify-content-between w-100 h-100\">\n                    <div class=\"d-flex flex-column\">\n                        \n                                                <div class=\"grid-item-title\">FETH\u0130YE<\/div>\n                                            <\/div>\n                    \n                                        <div class=\"d-flex align-items-center justify-content-between\">\n                        <div class=\"grid-item-text-link\">More details<\/div>\n                        <div class=\"grid-item-icon\">\n                            <i class=\"houzez-icon icon-arrow-button-right-2\"><\/i>\n                        <\/div>\n                    <\/div>\n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-idtkqb9jl elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"idtkqb9jl\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ry3nvs55a\" data-id=\"ry3nvs55a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-iubiyz1nu elementor-widget elementor-widget-spacer\" data-id=\"iubiyz1nu\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc19652 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bc19652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e07b461 elementor-widget elementor-widget-heading\" data-id=\"e07b461\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-large\">YOUR TRUSTED\nPARTNER FOR\nREAL ESTATE PURCHASES,\nSALES AND INVESTMENTS<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe7ee12 elementor-widget elementor-widget-text-editor\" data-id=\"fe7ee12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>We\u2019re here to help you find the property that best suits your needs, market your property at its true value, and guide you toward profitable investment opportunities.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7f7245 elementor-widget elementor-widget-button\" data-id=\"d7f7245\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hisarkayaemlak.com\/en\/portfolio\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VIEW OUR PORTFOLIO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-t2ec9pscw\" data-id=\"t2ec9pscw\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-g339zcd73 elementor-widget-mobile__width-auto elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"g339zcd73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-s3vbf3vzy elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"s3vbf3vzy\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ag9msopuh\" data-id=\"ag9msopuh\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f41d809 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f41d809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRESIDENTIAL AND LUXURY PROPERTIES\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFrom location to design, we help you find your dream living space through our carefully selected portfolio of residential and luxury properties.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f7c3d9 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4f7c3d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLAND AND PLOT CONSULTANCY\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWe closely monitor land and plots in high-growth potential areas, helping you identify the right investment timing and location.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a3c323 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3a3c323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCOMMERCIAL REAL ESTATE\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWe offer return-focused and sustainable options for clients looking for shops, offices, and commercial investment properties.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7t4j9z9c2 elementor-section-content-middle elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7t4j9z9c2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-pwzft3sqg\" data-id=\"pwzft3sqg\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-rclw2ssd2 elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"rclw2ssd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3027dbb elementor-widget elementor-widget-heading\" data-id=\"3027dbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CLIENT TESTIMONIALS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-74ej27sjm elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74ej27sjm\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-g2s00n7nm\" data-id=\"g2s00n7nm\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d142858 elementor-widget elementor-widget-image-box\" data-id=\"d142858\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Ahmet Y\u0131lmaz<\/h3><p class=\"elementor-image-box-description\">I spent a long time researching investment opportunities in the Fethiye area. The Hisarkaya Real Estate team did not just show me properties; they provided a genuine market analysis. Thanks to them, I made the right investment at the right price. Their transparency throughout the process also gave me great confidence.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a59e094\" data-id=\"a59e094\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d2b379 elementor-widget elementor-widget-image-box\" data-id=\"3d2b379\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Zeynep Karaca<\/h3><p class=\"elementor-image-box-description\">As it was my first time buying a home, I was very unsure at first, but the team explained the entire process in detail. They offered alternatives tailored entirely to my needs, without any unnecessary guidance or pressure. I received both a reliable and professional service.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f84198b\" data-id=\"f84198b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6910b4c elementor-widget elementor-widget-image-box\" data-id=\"6910b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Mehmet Demir<\/h3><p class=\"elementor-image-box-description\">I have worked with different real estate agencies before, but I clearly saw the difference here. I was very impressed by the way they spoke with real market data and explained the investment logic behind each option. We found the property I wanted in a short time. I would definitely recommend them.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1dalmgbj elementor-hidden-mobile elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"d1dalmgbj\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-frdamofga elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"frdamofga\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-grr655l0e\" data-id=\"grr655l0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-z182e2049 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"z182e2049\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c0665o2qc\" data-id=\"c0665o2qc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-xhik3u83f elementor-widget elementor-widget-spacer\" data-id=\"xhik3u83f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ojhx65g9 elementor-widget elementor-widget-heading\" data-id=\"5ojhx65g9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Discover our latest Properties<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-x11u5chdb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"x11u5chdb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-eqhto3b6b\" data-id=\"eqhto3b6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-lnl61ncm0 elementor-widget elementor-widget-spacer\" data-id=\"lnl61ncm0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Just Imagine It\u2014Leave the Rest to Us. A Guide to Real Estate Investment in Turkey ALL K\u0130RALIK SATILIK Search by Keyword Ad Type Make a SelectionVillaDaireKomple BinaTuristik TesisTicari GayrimenkulProjedenArsa &amp; Arazi REGION Make a SelectionFETH\u0130YE &#8211; \u00c7al\u0131\u015f (Mahalle) &#8211; Faralya (Mahalle) &#8211; Fethiye \u015eehir Merkezi (Mahalle) &#8211; G\u00f6cek (Mahalle) &#8211; Karag\u00f6zler (Mahalle) &#8211; Kayak\u00f6y (Mahalle) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-18810","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hisarkayaemlak.com\/en\/wp-json\/wp\/v2\/pages\/18810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hisarkayaemlak.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hisarkayaemlak.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hisarkayaemlak.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hisarkayaemlak.com\/en\/wp-json\/wp\/v2\/comments?post=18810"}],"version-history":[{"count":9,"href":"https:\/\/hisarkayaemlak.com\/en\/wp-json\/wp\/v2\/pages\/18810\/revisions"}],"predecessor-version":[{"id":21578,"href":"https:\/\/hisarkayaemlak.com\/en\/wp-json\/wp\/v2\/pages\/18810\/revisions\/21578"}],"wp:attachment":[{"href":"https:\/\/hisarkayaemlak.com\/en\/wp-json\/wp\/v2\/media?parent=18810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}